{"id":3247,"date":"-0001-11-30T00:00:00","date_gmt":"1969-12-31T19:00:00","guid":{"rendered":"http:\/\/giveneyestosee.com\/blog\/1969\/12\/tweet-tweet-todays-daily-twitter-summary-50\/"},"modified":"-0001-11-30T00:00:00","modified_gmt":"1969-12-31T19:00:00","slug":"tweet-tweet-todays-daily-twitter-summary-50","status":"publish","type":"post","link":"http:\/\/giveneyestosee.com\/blog\/0000\/00\/tweet-tweet-todays-daily-twitter-summary-50\/","title":{"rendered":"Tweet! Tweet! (Today&#8217;s Daily Twitter Summary)"},"content":{"rendered":"<ul class=\"ws_tweet_list\">\n<li class=\"ws_tweet\">In Like A Lion <a href=\"http:\/\/t.co\/ihPjHgfprw\" rel=\"nofollow\">http:\/\/t.co\/ihPjHgfprw<\/a> <a href=\"http:\/\/search.twitter.com\/search?q=%23Pics\">#Pics<\/a> of lioness, giraffe, cheetah and meerkat from this afternoon at <a href=\"http:\/\/twitter.com\/BuschGardens\">@BuschGardens<\/a> <a class=\"ws_tweet_time\" href=\"http:\/\/twitter.com\/memoryanddream\/statuses\/313133845543272448\">23:45:01, 2013-03-16<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>In Like A Lion http:\/\/t.co\/ihPjHgfprw #Pics of lioness, giraffe, cheetah and meerkat from this afternoon at @BuschGardens 23:45:01, 2013-03-16<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[453],"tags":[452,451],"class_list":["post-3247","post","type-post","status-publish","format-standard","hentry","category-twitter-2","tag-tweets","tag-twitter"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"http:\/\/giveneyestosee.com\/blog\/wp-json\/wp\/v2\/posts\/3247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/giveneyestosee.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/giveneyestosee.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/giveneyestosee.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/giveneyestosee.com\/blog\/wp-json\/wp\/v2\/comments?post=3247"}],"version-history":[{"count":0,"href":"http:\/\/giveneyestosee.com\/blog\/wp-json\/wp\/v2\/posts\/3247\/revisions"}],"wp:attachment":[{"href":"http:\/\/giveneyestosee.com\/blog\/wp-json\/wp\/v2\/media?parent=3247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/giveneyestosee.com\/blog\/wp-json\/wp\/v2\/categories?post=3247"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/giveneyestosee.com\/blog\/wp-json\/wp\/v2\/tags?post=3247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}